{"id":13984,"date":"2024-05-30T11:00:14","date_gmt":"2024-05-30T09:00:14","guid":{"rendered":"https:\/\/www.onyx-one.com\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/"},"modified":"2025-04-09T11:22:12","modified_gmt":"2025-04-09T09:22:12","slug":"verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern","status":"publish","type":"post","link":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/","title":{"rendered":"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern"},"content":{"rendered":"<p>Eine effiziente Zusammenarbeit mit ausl\u00e4ndischen Zulieferern in der Industrie erfordert einen tiefgreifenden Ansatz, der die Komplexit\u00e4t und die Risiken dieser Zusammenarbeit ber\u00fccksichtigt. Sie bringt verschiedene Herausforderungen und Verantwortlichkeiten mit sich, insbesondere im Hinblick auf die neuen gesetzlichen Anforderungen. In diesem Artikel gehen wir auf die wichtigsten Verpflichtungen und Bedenken ein, die Auftragnehmer ber\u00fccksichtigen m\u00fcssen, um die Vorschriften einzuhalten und die Risiken zu minimieren.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/subcontractors-1024x1024.png\" alt=\"\" class=\"wp-image-12469\" srcset=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/subcontractors-1024x1024.png 1024w, https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/subcontractors-300x300.png 300w, https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/subcontractors-150x150.png 150w, https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/subcontractors-768x768.png 768w, https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/subcontractors.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-vander-elst-freistellung-eine-losung-mit-bedingungen\">Vander Elst Freistellung,\r\neine L\u00f6sung mit Bedingungen<\/h2>\n\n\n\n<p class=\"has-ast-global-color-1-background-color has-background\">Der angespannte Arbeitsmarkt zwingt Unternehmen dazu, \u00fcber die nationalen Grenzen hinauszuschauen. Die Ausnahmeregelung nach Vander Elst, die auf einem Urteil des Gerichtshofs der Europ\u00e4ischen Union (Rechtssache C-43\/93) beruht, erm\u00f6glicht es Unternehmen in der EU, Arbeitnehmer aus Drittl\u00e4ndern (au\u00dferhalb des EWR und der Schweiz), die in einem EU-Mitgliedstaat rechtm\u00e4\u00dfig besch\u00e4ftigt sind, ohne zus\u00e4tzliche Arbeitserlaubnis vor\u00fcbergehend in anderen EU-Mitgliedstaaten zu besch\u00e4ftigen. Dies ist unter der Voraussetzung m\u00f6glich, dass die Arbeitnehmer rechtm\u00e4\u00dfig im Heimatland arbeiten und die Besch\u00e4ftigung im anderen Mitgliedstaat vor\u00fcbergehend ist. In Belgien gilt diese Ausnahmeregelung landesweit, und die Unternehmen m\u00fcssen nationale Verfahren wie die Limosa-Meldung befolgen, um die Vorschriften einzuhalten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-kettenhaftung\">Kettenhaftung <\/h2>\n\n\n\n<p class=\"has-ast-global-color-2-background-color has-background\">Auftragnehmer, die mit Subunternehmern aus Drittl\u00e4ndern zusammenarbeiten, sollten sich ihrer Haftung im Falle illegaler Besch\u00e4ftigung bewusst sein. Derzeit k\u00f6nnen sich Auftragnehmer von der Haftung befreien, indem sie eine schriftliche Erkl\u00e4rung des Subunternehmers einholen, in der dieser erkl\u00e4rt, dass er keine illegalen Einwanderer besch\u00e4ftigt. Die Haftung lebt jedoch wieder auf, wenn die Sozialkontrolle nachweist, dass der Auftragnehmer Kenntnis von der illegalen Besch\u00e4ftigung hatte.<\/p>\n\n\n\n<p class=\"has-ast-global-color-1-background-color has-background\"><strong>Neue Sorgfaltspflicht<\/strong>\r\n\r\nDie fl\u00e4mische Regierung hat zus\u00e4tzliche Verpflichtungen zur St\u00e4rkung der Kettenhaftung eingef\u00fchrt. Diese Sorgfaltspflicht verlangt von den Auftragnehmern, von ihren direkten Subunternehmern zus\u00e4tzliche Dokumente anzufordern, wie zum Beispiel:\r\n&#8211; Identifizierung und Kontaktdaten des Subunternehmers.\r\n&#8211; Pers\u00f6nliche Daten von ausl\u00e4ndischen Arbeitnehmern und Selbst\u00e4ndigen.\r\n&#8211; Erwartet werden: Identit\u00e4tsnachweise, Aufenthaltsgenehmigungen, Arbeitskarten und Limosa\r\n&#8211; Aufenthalts- und Arbeitsgenehmigungen.\r\n\r\nObwohl die genauen Anforderungen noch nicht festgelegt sind, wird erwartet, dass Identit\u00e4tsnachweise, Aufenthaltsgenehmigungen, Arbeitskarten und Limosa-Meldungen erforderlich sein werden. Obwohl sowohl Flandern als auch Wallonien Vorschriften zur Kettenhaftung und Sorgfaltspflicht haben, um Missbrauch bei der Besch\u00e4ftigung ausl\u00e4ndischer Arbeitnehmer zu verhindern, gibt es einige Unterschiede in der Strenge und den spezifischen Anforderungen:<\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Grad der Strenge<\/summary>\n<p class=\"has-ast-global-color-1-background-color has-background\"><strong>Flandern<\/strong>\r\nIm Allgemeinen strenger mit zus\u00e4tzlichen Sorgfaltspflichten. Spezielle Checklisten und Dokumente sind erforderlich, um die Einhaltung zu gew\u00e4hrleisten.\r\n<strong>Wallonien<\/strong>\r\nEbenfalls streng, aber m\u00f6glicherweise weniger detailliert in bestimmten Anforderungen. Der Schwerpunkt liegt auf \u00e4hnlichen Grunds\u00e4tzen, aber mit einigen Unterschieden in der Umsetzung.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Anforderungen an die Dokumentation<\/summary>\n<p class=\"has-ast-global-color-2-background-color has-background\"><strong>Flandern<\/strong>\r\nSpezifische Anforderungen f\u00fcr die Anforderung von Identifikations- und Kontaktinformationen von Unterauftragnehmern.\r\nBetonung des Bedarfs an pers\u00f6nlichen Daten ausl\u00e4ndischer Arbeitnehmer, einschlie\u00dflich Aufenthalts- und Arbeitserlaubnis.\r\nStrenge Durchsetzung der Limosa-Meldung.\r\n<strong>Wallonien<\/strong>\r\nVerlangt ebenfalls die Identifizierung von Subunternehmern und Kontaktinformationen.\r\nSchwerpunkt auf der Erlangung von Aufenthalts- und Arbeitsgenehmigungen, aber m\u00f6glicherweise weniger spezifische Anforderungen f\u00fcr zus\u00e4tzliche Dokumente wie Arbeitskarten.<\/p>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/details>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Control levels &amp; inspections<\/summary>\n<p class=\"has-ast-global-color-1-background-color has-background\"><strong>Flandern<\/strong>\r\nDie Auftragnehmer m\u00fcssen aktiv pr\u00fcfen, ob die Dokumente g\u00fcltig sind und der Realit\u00e4t entsprechen.\r\nGezielte Kontrolle der G\u00fcltigkeitsdauer von Aufenthalts- und Arbeitsgenehmigungen.\r\n\r\nStrenge Inspektionen und Durchsetzung durch Kontrollstellen. Die Auftragnehmer m\u00fcssen die Einhaltung aller Sorgfaltspflichten nachweisen k\u00f6nnen. Hohe Bu\u00dfgelder und Strafen bei Nichteinhaltung.\r\n<strong>Wallonien<\/strong>\r\nVerlangt die Kontrolle von Dokumenten, aber die genauen Kontrollma\u00dfnahmen k\u00f6nnen etwas weniger streng sein als in Flandern.\r\nVerfallsdaten m\u00fcssen verfolgt werden, aber die Betonung der aktiven Kontrolle kann weniger intensiv sein.\r\nAuch hier sind Inspektionen vorgeschrieben, aber die Durchsetzung kann im Vergleich zu Flandern etwas weniger streng sein. Bu\u00dfgelder und Strafen sind vorhanden, aber H\u00e4ufigkeit und Intensit\u00e4t der Inspektionen k\u00f6nnen variieren.<\/p>\n<\/details>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-niederlande\">Niederlande<\/h4>\n\n\n\n<p class=\"has-ast-global-color-2-background-color has-background\"><strong>Wet ketenaansprakelijkheid (WKA)<\/strong>\r\nDie Auftragnehmer sind f\u00fcr die Einhaltung der Vorschriften f\u00fcr die Besch\u00e4ftigung ausl\u00e4ndischer Arbeitnehmer verantwortlich. Sie m\u00fcssen darauf achten, dass sie die entsprechenden Dokumente wie Arbeitserlaubnis und Aufenthaltsgenehmigung anfordern.<\/p>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-deutschland\">Deutschland<\/h4>\n\n\n\n<p class=\"has-ast-global-color-5-background-color has-background\"><strong>Arbeitnehmer-Entsendegesetz (AEntG)<\/strong>\r\nDas AEntG regelt die Besch\u00e4ftigung ausl\u00e4ndischer Arbeitnehmer und \u00fcbertr\u00e4gt dem Unternehmer die Verantwortung f\u00fcr die Pr\u00fcfung der Arbeitserlaubnis, des Aufenthaltsstatus und anderer relevanter Dokumente.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-nbsp-frankreich\">&nbsp;\r\n\r\nFrankreich<\/h4>\n\n\n\n<p class=\"has-ast-global-color-1-background-color has-background\"><strong>Gesetz Macron<\/strong>\r\nUnternehmen, die ausl\u00e4ndische Arbeitskr\u00e4fte einstellen, m\u00fcssen strenge Dokumentationsanforderungen erf\u00fcllen, einschlie\u00dflich Arbeitserlaubnis, Aufenthaltsgenehmigung und Einhaltung der Mindestlohnvorschriften.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-vereinigtes-konigreich\">Vereinigtes K\u00f6nigreich<\/h4>\n\n\n\n<p class=\"has-ast-global-color-2-background-color has-background\"><strong>Gesetz \u00fcber Einwanderung, Asyl und Staatsangeh\u00f6rigkeit 2006<\/strong>\r\nArbeitgeber m\u00fcssen den Aufenthaltsstatus und die Arbeitserlaubnis von ausl\u00e4ndischen Arbeitnehmern \u00fcberpr\u00fcfen und sind f\u00fcr die Einhaltung der Einwanderungsgesetze verantwortlich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-uberlegungen-bei-der-zusammenarbeit-mit-auslandischen-unterauftragnehmern\">\u00dcberlegungen bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern<\/h2>\n\n\n\n<p class=\"has-ast-global-color-1-background-color has-background\">Neben der Vander-Elst-Befreiung m\u00fcssen die Auftragnehmer weitere administrative Verpflichtungen beachten. So muss ein ausl\u00e4ndischer Arbeitnehmer f\u00fcr eine Besch\u00e4ftigung auf belgischem Hoheitsgebiet eine Karte nach Schema 3 oder Schema 15\/A vorlegen k\u00f6nnen.\r\nDerzeit wird eine digitale Datenbank nach dem Prinzip \u201enur einmal\u201c aufgebaut, die daf\u00fcr sorgt, dass Dokumente, die sich bereits im Besitz der Beh\u00f6rden befinden, nicht erneut angefordert werden m\u00fcssen.\r\nWenn der Subunternehmer die erforderlichen Daten nicht vorlegt, muss der Auftragnehmer ihn einmal daran erinnern und, falls die Dokumente nicht vorgelegt werden, die Kontrolle informieren. Die Sorgfaltspflicht beinhaltet keine rechtliche Verpflichtung zur Kontrolle, verlangt aber die \u00dcberpr\u00fcfung der G\u00fcltigkeit von Dokumenten wie Aufenthalts- und Arbeitsgenehmigungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-ast-global-color-0-color has-text-color has-link-color wp-elements-83464b30fae7b1ec5038e321ba955a29\" id=\"h-ein-intelligenter-ansatz-mit-onyx-one\">Ein intelligenter Ansatz mit Onyx One<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Die Zusammenarbeit mit ausl\u00e4ndischen Subunternehmern erfordert ein sorgf\u00e4ltiges Vorgehen, um die rechtlichen Verpflichtungen zu erf\u00fcllen und die Kettenhaftung sicherzustellen. Die Implementierung dieser Dokumentationsprozesse kann komplex und zeitaufw\u00e4ndig sein. Gl\u00fccklicherweise bietet Onyx One eine L\u00f6sung, die diesen Prozess vereinfacht und automatisiert. Gerne erz\u00e4hlen wir Ihnen mehr dar\u00fcber<\/p>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-style-shadow has-ast-global-color-7-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-sowmedia-animated-background is-type-circle is-position-left-top\">\n\n    \n        <svg preserveAspectRatio=\"none\" viewBox=\"0 0 1000 1000\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\">\n            <g id=\"Page-1\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\" style=\"opacity:1;\">\n                <circle id=\"Oval\" stroke=\"var(--ast-global-color-2)\" stroke-width=\"100\" cx=\"500\" cy=\"500\" r=\"450\"><\/circle>\n            <\/g>\n        <\/svg>\n\n    \n\n<\/div>\n\n\n\n<h3 class=\"has-large-font-size wp-block-heading\">WARUM<\/h3>\n\n\n\n<h5 class=\"wp-block-heading\">WIR GLAUBEN AN DIE ZUSAMMENARBEIT<\/h5>\n\n\n\n<p>Ich glaube, die Welt ist besser dran, wenn JEDER das tut, was er gerne tut<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jeder tut das, was er am besten kann<\/li>\n\n\n\n<li>Wir k\u00f6nnen uns auf das konzentrieren, was wir am besten k\u00f6nnen<\/li>\n\n\n\n<li>Wir haben die M\u00f6glichkeit, uns zu spezialisieren, was&nbsp;bedeutet, dass wir andere brauchen, um das zu tun, was wir lieber nicht tun w\u00fcrden, und dass die Zusammenarbeit unerl\u00e4sslich ist.<br>Kurz gesagt, ich glaube, die Welt ist besser dran, wenn wir zusammenarbeiten. Zusammenarbeiten, damit die Ressourcen effizient und nachhaltig genutzt werden. Zusammenarbeiten mit unseren Kollegen, Lieferanten, Kunden und Vertriebskan\u00e4len. Zusammenarbeiten mit Spezialisten, Beratern und Auftragnehmern sowie mit den Beh\u00f6rden in einem Regelungsrahmen.<\/li>\n\n\n\n<li>Zusammenarbeiten als Einzelperson in einem Team<\/li>\n\n\n\n<li>Zusammenarbeiten als Team in einer Organisation<\/li>\n\n\n\n<li>Zusammenarbeiten als Unternehmen in der Gesellschaft<\/li>\n\n\n\n<li>Ich glaube, dass eine Zusammenarbeit realisiert werden kann, wenn wir uns selbst entwickeln k\u00f6nnen. Zusammenarbeit ist m\u00f6glich, wenn wir:<\/li>\n\n\n\n<li>auf unseren Auftrag vorbereitet sind<\/li>\n\n\n\n<li>wissen, was von uns erwartet wird<\/li>\n\n\n\n<li>die Autonomie haben, (die richtigen) Entscheidungen zu treffen<\/li>\n\n\n\n<li>wissen, dass das, was wir andere tun lassen, gut gemacht wird<\/li>\n\n\n\n<li>darauf vertrauen k\u00f6nnen, dass andere ebenfalls vorbereitet sind, sich weiterentwickelt haben und wissen, was von ihnen erwartet wird<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-shadow has-ast-global-color-7-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"has-large-font-size wp-block-heading\">WAS<\/h3>\n\n\n\n<h5 class=\"wp-block-heading\">WIR GLAUBEN AN QUALIT\u00c4T UND EHRLICHKEIT<\/h5>\n\n\n\n<p class=\"is-style-subtitle\">Wir glauben, dass Arbeit und Zusammenarbeit nur m\u00f6glich sind auf der Basis von:<\/p>\n\n\n\n<p class=\"is-style-subtitle\">Wir glauben, dass Arbeit und Zusammenarbeit nur m\u00f6glich sind auf der Basis von:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gleichwertigkeit<\/li>\n\n\n\n<li>Bescheidenheit<\/li>\n\n\n\n<li>Selbst\u00e4ndigkeit<\/li>\n\n\n\n<li>Respekt<\/li>\n\n\n\n<li>Wertsch\u00e4tzung<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<p>Wir glauben, dass sich Produkte und Dienstleistungen auszeichnen k\u00f6nnen durch unsere:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aufmerksamkeit<\/li>\n\n\n\n<li>Sorgfalt<\/li>\n\n\n\n<li>Professionalit\u00e4t<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p>Wir bieten Unterst\u00fctzung und stehen f\u00fcr:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Eigenheit<\/li>\n\n\n\n<li>Originalit\u00e4t<\/li>\n\n\n\n<li>Flexibilit\u00e4t<\/li>\n\n\n\n<li>Spa\u00df<\/li>\n<\/ul>\n\n\n\n<p>Wir glauben daran, dass wir einen positiven Beitrag zu unserer Gesellschaft und der Welt im Allgemeinen leisten k\u00f6nnen.<\/p>\n\n\n\n<p>Wir glauben, dass unsere Fokussierung auf die Informationssicherheit gem\u00e4\u00df ISO 27001 und der DSGVO einen Mehrwert f\u00fcr unsere Kunden darstellt, u. a. durch:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Privacy by design (eingebauter Datenschutz)<\/li>\n\n\n\n<li>Privacy by default (datenschutzfreundliche Standardeinstellungen)<\/li>\n\n\n\n<li>Zusammenarbeit mit der Aufsichtsbeh\u00f6rde, falls erforderlich<\/li>\n\n\n\n<li>Unsere Rolle als Verarbeiter und f\u00fcr die Verarbeitung Verantwortlicher ordnungsgem\u00e4\u00df zu erf\u00fcllen<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-shadow has-ast-global-color-7-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-sowmedia-animated-background is-type-circle is-position-left-bottom\">\n\n    \n        <svg preserveAspectRatio=\"none\" viewBox=\"0 0 1000 1000\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\">\n            <g id=\"Page-1\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\" style=\"opacity:1;\">\n                <circle id=\"Oval\" stroke=\"var(--ast-global-color-2)\" stroke-width=\"100\" cx=\"500\" cy=\"500\" r=\"450\"><\/circle>\n            <\/g>\n        <\/svg>\n\n    \n\n<\/div>\n\n\n\n<h3 class=\"has-large-font-size wp-block-heading\">WIE<\/h3>\n\n\n\n<h5 class=\"wp-block-heading\">WIR GLAUBEN AN TECHNOLOGIE UND EFFIZIENZ<\/h5>\n\n\n\n<p>Wir helfen Unternehmen dabei:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ihre Mitarbeiter zu schulen<\/li>\n\n\n\n<li>den Schulungsprozess effizient zu gestalten<\/li>\n\n\n\n<li>einen Einblick in die Entwicklung ihrer Mitarbeiter zu erhalten<\/li>\n<\/ul>\n\n\n\n<p>Aus diesem Grund entwickeln wir e-Learning und bieten wir die Onyx-Lernumgebung an.<\/p>\n\n\n\n<p>Wir helfen Auftraggeber dabei:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ihre Fremdfirmen zu schulen und zu qualifizieren<\/li>\n\n\n\n<li>einen Einblick in die Kompetenzen ihrer Fremdfirmen zu erhalten<\/li>\n\n\n\n<li>vorbereitet zu sein, wenn Fremdfirmen zur Arbeit kommen, um ihre Teams zu leiten<\/li>\n<\/ul>\n\n\n\n<p>Wir helfen Fremdfirmen dabei:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sich vor Arbeitsbeginn effizient vorzubereiten<\/li>\n\n\n\n<li>ihre Verwaltung zu vereinfachen<\/li>\n<\/ul>\n\n\n\n<p>Wir helfen Produzenten dabei:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ihren Vertriebskanal zu schulen<\/li>\n\n\n\n<li>ihre Kunden zu informieren<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Deshalb entwickeln wir Onyx One und schaffen eine Online-Community der effizientesten Unternehmen.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns alignwide is-style-default is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"wp-block-quote has-text-align-center is-style-shadow has-ast-global-color-7-background-color has-background has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eWir empfehlen Onyx One ohne jeden Zweifel weiter! Viele unserer Hausbauunternehmen arbeiten bereits mit dem System und das hat uns \u00fcberzeugt. Wir sind mit der Plattform und mit der Zusammenarbeit zufrieden.\u201c<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/11\/Bayer.svg\" alt=\"\" class=\"wp-image-8246\" style=\"width:50px;height:98px\"\/><\/figure>\n<cite><strong>Fons Huybrechts<\/strong>\nBerater f\u00fcr betriebliche Pr\u00e4vention &#8211; Bayer Agriculture bv<\/cite><\/blockquote>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"wp-block-quote has-text-align-center is-style-shadow has-ast-global-color-7-background-color has-background has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eOnyx One hat unsere Auftragnehmerverwaltung erheblich verbessert. Alle Dokumente und Bescheinigungen werden jetzt automatisch nachverfolgt. Es ist ein benutzerfreundliches System und hat einen starken Service Desk.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"218\" height=\"102\" src=\"\/wp-content\/uploads\/2022\/11\/Monument.png\" alt=\"\" class=\"wp-image-8250\" style=\"width:100px\"\/><\/figure>\n<cite><strong>Diana De Peuter<\/strong>\nLeiterin Finanzen und IT &#8211; Monument Chemical bv<\/cite><\/blockquote>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"wp-block-quote has-text-align-center is-style-shadow has-ast-global-color-7-background-color has-background has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eWir haben ein hervorragendes Sicherheitstraining (e-Learning) f\u00fcr die Auftragnehmer durch Onyx One, und die Zusammenarbeit funktioniert reibungslos.\u201c<\/p>\n<cite><strong><strong><strong>Luc Dejonghe<\/strong><br><\/strong><\/strong>HSSE Manager&nbsp; &#8211; Shell Catalysts &amp; Technologies Belgium N.V.<\/cite><\/blockquote>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-lcb-logo-carousel alcb__84b16c14 alignwide\"><div dir=\"ltr\" class=\"alcb__carousel_container swiper\" data-desktop=\"6\" data-tablet=\"4\" data-mobile=\"2\" data-autoplay=\"true\" data-autoplaydelay=\"2000\" data-autoplaydirection=\"false\" data-speed=\"700\" data-loop=\"true\" data-pauseonhover=\"true\" data-keyboard=\"false\" data-mousewheel=\"false\" data-autoheight=\"false\" data-deskspace=\"50\" data-tabspace=\"20\" data-phonespace=\"10\" data-id=\"alcb__84b16c14\" data-pagination=\"false\" data-navigation=\"false\" id=\"alcb__84b16c14\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/ajinomoto-logo.png\" alt=\"\" id=\"8299\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/logo-Umicore.jpeg\" alt=\"\" id=\"8295\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/logo-borealis.jpeg\" alt=\"\" id=\"8286\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/rousselot-logo-vector.png\" alt=\"\" id=\"8277\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/Nyrstar-logo.gif\" alt=\"\" id=\"8265\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/Monument.png\" alt=\"\" id=\"8253\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/Bayer.svg\" alt=\"\" id=\"8249\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/Aecom.png\" alt=\"\" id=\"8305\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/LOGO_ISS.png\" alt=\"\" id=\"8310\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/campine.png\" alt=\"\" id=\"8314\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/Evonik_logo.jpeg\" alt=\"\" id=\"8322\"\/><\/div><\/div><div class=\"swiper-slide alcb__logo-item\" style=\"border: 0 solid #333333;border-radius:0px\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2022\/11\/Smet.png\" alt=\"\" id=\"8331\"\/><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12457,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[212,192],"tags":[],"class_list":["post-13984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uitgelicht-de","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern - Onyx One<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern - Onyx One\" \/>\n<meta property=\"og:description\" content=\"[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/\" \/>\n<meta property=\"og:site_name\" content=\"Onyx One\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-30T09:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T09:22:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-30-at-10.56.30.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1096\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"marjan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marjan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/\"},\"author\":{\"name\":\"marjan\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#\\\/schema\\\/person\\\/1e708676d3f552f32c80792a4aba3547\"},\"headline\":\"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern\",\"datePublished\":\"2024-05-30T09:00:14+00:00\",\"dateModified\":\"2025-04-09T09:22:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/\"},\"wordCount\":1047,\"publisher\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onyx-one.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Screenshot-2024-05-30-at-10.56.30.png\",\"articleSection\":[\"Uitgelicht\",\"Unkategorisiert\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/\",\"url\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/\",\"name\":\"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern - Onyx One\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onyx-one.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Screenshot-2024-05-30-at-10.56.30.png\",\"datePublished\":\"2024-05-30T09:00:14+00:00\",\"dateModified\":\"2025-04-09T09:22:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.onyx-one.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Screenshot-2024-05-30-at-10.56.30.png\",\"contentUrl\":\"https:\\\/\\\/www.onyx-one.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Screenshot-2024-05-30-at-10.56.30.png\",\"width\":1096,\"height\":424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/\",\"name\":\"Onyx One\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#organization\",\"name\":\"Onyx One\",\"url\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.onyx-one.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo_OnyxOne_transparant-1024x176-1.png\",\"contentUrl\":\"https:\\\/\\\/www.onyx-one.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo_OnyxOne_transparant-1024x176-1.png\",\"width\":1024,\"height\":176,\"caption\":\"Onyx One\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/20474573\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.onyx-one.com\\\/de\\\/#\\\/schema\\\/person\\\/1e708676d3f552f32c80792a4aba3547\",\"name\":\"marjan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78b8b33565926b7c0daa0517e4fc076a81a7947161593cfe5ecc06b5caae107e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78b8b33565926b7c0daa0517e4fc076a81a7947161593cfe5ecc06b5caae107e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78b8b33565926b7c0daa0517e4fc076a81a7947161593cfe5ecc06b5caae107e?s=96&d=mm&r=g\",\"caption\":\"marjan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern - Onyx One","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/","og_locale":"de_DE","og_type":"article","og_title":"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern - Onyx One","og_description":"[&hellip;]","og_url":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/","og_site_name":"Onyx One","article_published_time":"2024-05-30T09:00:14+00:00","article_modified_time":"2025-04-09T09:22:12+00:00","og_image":[{"width":1096,"height":424,"url":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-30-at-10.56.30.png","type":"image\/png"}],"author":"marjan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marjan","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#article","isPartOf":{"@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/"},"author":{"name":"marjan","@id":"https:\/\/www.onyx-one.com\/de\/#\/schema\/person\/1e708676d3f552f32c80792a4aba3547"},"headline":"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern","datePublished":"2024-05-30T09:00:14+00:00","dateModified":"2025-04-09T09:22:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/"},"wordCount":1047,"publisher":{"@id":"https:\/\/www.onyx-one.com\/de\/#organization"},"image":{"@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-30-at-10.56.30.png","articleSection":["Uitgelicht","Unkategorisiert"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/","url":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/","name":"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern - Onyx One","isPartOf":{"@id":"https:\/\/www.onyx-one.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#primaryimage"},"image":{"@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-30-at-10.56.30.png","datePublished":"2024-05-30T09:00:14+00:00","dateModified":"2025-04-09T09:22:12+00:00","breadcrumb":{"@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#primaryimage","url":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-30-at-10.56.30.png","contentUrl":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-30-at-10.56.30.png","width":1096,"height":424},{"@type":"BreadcrumbList","@id":"https:\/\/www.onyx-one.com\/de\/verpflichtungen-und-bedenken-bei-der-zusammenarbeit-mit-auslaendischen-unterauftragnehmern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.onyx-one.com\/de\/"},{"@type":"ListItem","position":2,"name":"Verpflichtungen und Bedenken bei der Zusammenarbeit mit ausl\u00e4ndischen Unterauftragnehmern"}]},{"@type":"WebSite","@id":"https:\/\/www.onyx-one.com\/de\/#website","url":"https:\/\/www.onyx-one.com\/de\/","name":"Onyx One","description":"","publisher":{"@id":"https:\/\/www.onyx-one.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onyx-one.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.onyx-one.com\/de\/#organization","name":"Onyx One","url":"https:\/\/www.onyx-one.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.onyx-one.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/Logo_OnyxOne_transparant-1024x176-1.png","contentUrl":"https:\/\/www.onyx-one.com\/wp-content\/uploads\/2024\/06\/Logo_OnyxOne_transparant-1024x176-1.png","width":1024,"height":176,"caption":"Onyx One"},"image":{"@id":"https:\/\/www.onyx-one.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/20474573"]},{"@type":"Person","@id":"https:\/\/www.onyx-one.com\/de\/#\/schema\/person\/1e708676d3f552f32c80792a4aba3547","name":"marjan","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/78b8b33565926b7c0daa0517e4fc076a81a7947161593cfe5ecc06b5caae107e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78b8b33565926b7c0daa0517e4fc076a81a7947161593cfe5ecc06b5caae107e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78b8b33565926b7c0daa0517e4fc076a81a7947161593cfe5ecc06b5caae107e?s=96&d=mm&r=g","caption":"marjan"}}]}},"_links":{"self":[{"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/posts\/13984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/comments?post=13984"}],"version-history":[{"count":2,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/posts\/13984\/revisions"}],"predecessor-version":[{"id":14576,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/posts\/13984\/revisions\/14576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/media\/12457"}],"wp:attachment":[{"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/media?parent=13984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/categories?post=13984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onyx-one.com\/de\/wp-json\/wp\/v2\/tags?post=13984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}